{"id":101274,"date":"2021-11-07T11:07:44","date_gmt":"2021-11-07T14:07:44","guid":{"rendered":"https:\/\/www.locoxelrojo.com\/independiente\/?p=101274"},"modified":"2021-11-07T11:07:44","modified_gmt":"2021-11-07T14:07:44","slug":"convirtio-tras-28-partidos","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2021\/11\/07\/convirtio-tras-28-partidos\/","title":{"rendered":"\u00a1Convirti\u00f3 tras 28 partidos!"},"content":{"rendered":"<p>El triunfo de ayer frente a Arsenal no solo sirvi\u00f3 para no perderle pisada al pelot\u00f3n que lucha por el ingreso a la Copa Libertadores del a\u00f1o que viene sino para que <strong>Alan Velasco<\/strong> le ponga fin a una racha adversa.<\/p>\n<p><a href=\"https:\/\/www.locoxelrojo.com\/independiente\/2021\/11\/01\/una-joya-sin-gol\/\">Mucho se hab\u00eda hablado del poco gol que ten\u00eda la Joya<\/a>. Sus intermitencias a lo largo de los partidos, su falta de claridad y criterio para los metros finales y la punter\u00eda hab\u00edan atentado contra <strong>el pibe de 19 a\u00f1os que no convert\u00eda desde el 4 de mayo<\/strong>. Su \u00faltimo grito hab\u00eda sido en el empate 2-2 ante Bah\u00eda, en Brasil.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/fXCMUyNtGWE?start=52\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>Desde entonces Velasco tard\u00f3 28 encuentros y acumul\u00f3 2.186 minutos para volver a convertir<\/strong>. A lo largo de esta sequ\u00eda, <strong>el atacante promedi\u00f3 casi 80&#8242; por partido y dio 4 asistencias<\/strong>. Tiempo tuvo, est\u00e1 claro. Pero el arco se le hab\u00eda cerrado completamente.<\/p>\n<p>Hasta ayer, cuando a los 11 minutos del complemento, Independiente agarr\u00f3 mal parado a Arsenal y Alan se reencontr\u00f3 con el gol. <strong>Freno en seco para sacarse de encima la marca de Ignacio Gariglio y definici\u00f3n al palo m\u00e1s alejado de Alejandro Medina<\/strong>. Golazo.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/AllPxhTifUo\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><a href=\"https:\/\/www.locoxelrojo.com\/independiente\/2021\/11\/06\/velasco-el-gol-fue-una-alegria-inmensa\/\">Una vez finalizado el encuentro, Velasco explic\u00f3 el motivo de su emoci\u00f3n en su tanto<\/a>. <strong>&#8220;El gol fue una alegr\u00eda inmensa. Fue muy especial para mi porque la semana pasada falleci\u00f3 mi primo y el gol es para \u00e9l y para toda la familia&#8221;<\/strong>, manifest\u00f3. \u00a1Vamos, Alan!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El triunfo de ayer frente a Arsenal no solo sirvi\u00f3 para no perderle pisada al pelot\u00f3n que lucha por el ingreso a la Copa Libertadores del a\u00f1o que viene sino para que Alan Velasco le ponga fin a una racha adversa. Mucho se hab\u00eda hablado del poco gol que ten\u00eda la Joya. Sus intermitencias a [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":101275,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1989,3247],"tags":[3560,1099,1933,153,4555,4931,1808],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/101274"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=101274"}],"version-history":[{"count":1,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/101274\/revisions"}],"predecessor-version":[{"id":101276,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/101274\/revisions\/101276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/101275"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=101274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=101274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=101274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}