{"id":105712,"date":"2022-05-26T15:53:46","date_gmt":"2022-05-26T18:53:46","guid":{"rendered":"https:\/\/www.locoxelrojo.com\/independiente\/?p=105712"},"modified":"2022-05-26T15:55:10","modified_gmt":"2022-05-26T18:55:10","slug":"las-claves-de-la-durisima-derrota-contra-ceara","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2022\/05\/26\/las-claves-de-la-durisima-derrota-contra-ceara\/","title":{"rendered":"Las claves de la dur\u00edsima derrota contra Cear\u00e1"},"content":{"rendered":"<p><a href=\"https:\/\/www.locoxelrojo.com\/independiente\/2022\/05\/25\/independiente-vergonzosa-eliminacion-ceara\/\"><strong>Independiente perdi\u00f3 2-0 ante Cear\u00e1 en Avellaneda y qued\u00f3 eliminado de la Copa Sudamericana 2022<\/strong><\/a>. En <strong>LocoXelRojo<\/strong> analizamos las claves del partido.<\/p>\n<p><strong>Mal planteo<\/strong>: El esquema que propuso Eduardo Dom\u00ednguez de entrada no fue convincente ni tampoco influyente en el rendimiento general del equipo. Como a lo largo del semestre el Rojo lo padeci\u00f3 y cuando el DT se dio cuenta ya era tarde. Regal\u00f3 45 minutos<\/p>\n<p><strong>No estuvieron a la altura<\/strong>: El partido de anoche era trascendental para &#8220;salvar&#8221; y cubrir -si se quiere- la p\u00e9sima primera parte del a\u00f1o. Sin embargo, no hubo actitud (m\u00e1s all\u00e1 del auspicioso arranque), varios futbolistas estuvieron nerviosos y, en muchos casos, cometiendo groseros errores defensivos.<\/p>\n<p><strong>Sin remates no hay goles<\/strong>: De entrada el equipo de Dom\u00ednguez ten\u00eda la obligaci\u00f3n de ganar y con diferencia de 2 goles. No obstante, no consigui\u00f3 ninguno de los dos anteriores, pero la cuesti\u00f3n no queda solamente ah\u00ed: al cabo de 90 minutos Independiente pate\u00f3 3 veces con direcci\u00f3n al arco de Jo\u00e3o Ricardo. Quiz\u00e1s uno de los d\u00e9ficits en estos primeros 5 meses del a\u00f1o: la concreci\u00f3n.<\/p>\n<p><strong>Desmedidos<\/strong>: Alex Vigo, Andr\u00e9s Roa y Dami\u00e1n Batallini habr\u00e1n sido de lo peor en una noche negra y fr\u00eda para Independiente. Ninguno aport\u00f3 ni en ataque como en defensa y se sinti\u00f3 en la primera parte. L\u00f3gicamente en el complemento fueron reemplazados, pero, otra vez, ya era tarde para revertir la situaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Independiente perdi\u00f3 2-0 ante Cear\u00e1 en Avellaneda y qued\u00f3 eliminado de la Copa Sudamericana 2022. En LocoXelRojo analizamos las claves del partido. Mal planteo: El esquema que propuso Eduardo Dom\u00ednguez de entrada no fue convincente ni tampoco influyente en el rendimiento general del equipo. Como a lo largo del semestre el Rojo lo padeci\u00f3 y [&hellip;]<\/p>\n","protected":false},"author":101027,"featured_media":105713,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[7,3247],"tags":[5121,4267,153,4872,4294,2207,4820],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/105712"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/101027"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=105712"}],"version-history":[{"count":1,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/105712\/revisions"}],"predecessor-version":[{"id":105714,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/105712\/revisions\/105714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/105713"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=105712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=105712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=105712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}