{"id":108888,"date":"2022-10-16T19:20:19","date_gmt":"2022-10-16T22:20:19","guid":{"rendered":"https:\/\/www.locoxelrojo.com\/independiente\/?p=108888"},"modified":"2022-10-16T21:16:44","modified_gmt":"2022-10-17T00:16:44","slug":"falcioni-les-di-carta-blanca","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2022\/10\/16\/falcioni-les-di-carta-blanca\/","title":{"rendered":"Falcioni: &#8220;Les di carta blanca para que busquen lo mejor para el club&#8221;"},"content":{"rendered":"<p>Luego del <a href=\"https:\/\/www.locoxelrojo.com\/independiente\/2022\/10\/16\/batallo-y-volvio-al-triunfo\/\">triunfo 1-0 ante Banfield<\/a>, <strong>Julio C\u00e9sar Falcioni anunci\u00f3 que habl\u00f3 con la dirigencia y se pondr\u00e1 a disposici\u00f3n para arreglar su salida<\/strong> al finalizar la Liga Profesional.<\/p>\n<p>El Emperador fue contundente: <strong>\u201cHe hablado con los dirigentes. Les di carta blanca para que busquen lo mejor para el club. Dirigir\u00e9 ante Boca y luego se juntar\u00e1n con mi representante, no va a haber ning\u00fan problema para arreglar&#8221;.<\/strong><\/p>\n<p>Adem\u00e1s, sobre la decisi\u00f3n dirigencial, aclar\u00f3: <strong>\u201cHicieron lo correcto, vinieron a hablar cara a cara. Si contin\u00fao, las decisiones las tomar\u00e9 yo. Si no contin\u00fao, ninguna de las decisiones que se tomen van a ser m\u00edas\u201d.<\/strong><\/p>\n<p><strong>\u201cA la gente le digo que seguramente me hubiese gustado hacer m\u00e1s de lo que pudimos hacer. Agarramos al equipo en la posici\u00f3n 26 y hoy estamos 13. No es una buena posici\u00f3n, no estamos conformes. Me hubiese gustado terminar m\u00e1s arriba. Hicimos lo que pudimos\u201d<\/strong>, manifest\u00f3 Falcioni.<\/p>\n<p>Por \u00faltimo, dej\u00f3 un claro mensaje sobre la visita a la Bombonera y se expres\u00f3 sobre el triunfo: <strong>\u201cLas conjeturas son solamente period\u00edsticas. Los jugadores van al frente, iremos a jugar a la Bombonera. Hoy nos cost\u00f3 manejar la pelota, est\u00e1bamos muy apurados, volvieron algunos jugadores importantes y lo hicieron muy bien. Lo mejor que tenemos es el ida y vuelta con ellos d\u00eda a d\u00eda y el esfuerzo que hacen en cada partido&#8221;.<\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\">&#8220;Volvieron algunos jugadores importantes y lo hicieron muy bien. Lo mejor que tenemos es el ida y vuelta con ellos d\u00eda a d\u00eda y el esfuerzo que hacen en cada partido&#8221;.<\/p>\n<p>&#x1f399;&#xfe0f; <a href=\"https:\/\/twitter.com\/JulioFalcioniDT?ref_src=twsrc%5Etfw\">@juliofalcionidt<\/a> en conferencia de prensa <a href=\"https:\/\/t.co\/uUar1WXpnS\">pic.twitter.com\/uUar1WXpnS<\/a><\/p>\n<p>\u2014 C. A. Independiente (@Independiente) <a href=\"https:\/\/twitter.com\/Independiente\/status\/1581793652669489152?ref_src=twsrc%5Etfw\">October 16, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego del triunfo 1-0 ante Banfield, Julio C\u00e9sar Falcioni anunci\u00f3 que habl\u00f3 con la dirigencia y se pondr\u00e1 a disposici\u00f3n para arreglar su salida al finalizar la Liga Profesional. El Emperador fue contundente: \u201cHe hablado con los dirigentes. Les di carta blanca para que busquen lo mejor para el club. Dirigir\u00e9 ante Boca y luego [&hellip;]<\/p>\n","protected":false},"author":101029,"featured_media":108889,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3247,3],"tags":[153,5067,385,5193],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/108888"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/101029"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=108888"}],"version-history":[{"count":4,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/108888\/revisions"}],"predecessor-version":[{"id":108893,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/108888\/revisions\/108893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/108889"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=108888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=108888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=108888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}