{"id":117856,"date":"2024-02-28T19:23:18","date_gmt":"2024-02-28T22:23:18","guid":{"rendered":"https:\/\/www.locoxelrojo.com\/independiente\/?p=117856"},"modified":"2024-02-28T19:23:18","modified_gmt":"2024-02-28T22:23:18","slug":"sayago-suma-minutos-y-convierte","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2024\/02\/28\/sayago-suma-minutos-y-convierte\/","title":{"rendered":"Sayago, suma minutos y convierte"},"content":{"rendered":"<p><strong>David Sayago lleva 2 tantos convertidos en 4 partidos con la camiseta de Defensores de Belgrano.<\/strong><\/p>\n<p>El delantero, que todav\u00eda pertenece a Independiente, fue al Drag\u00f3n a buscar los minutos que no iba a tener en el Rojo. <strong>Por suerte los est\u00e1 logrando y se dio el lujo de poder marcar<\/strong>.<\/p>\n<p>Su mejor versi\u00f3n la mostr\u00f3 <strong>frente a Deportivo Mor\u00f3n, donde convirti\u00f3 dos goles<\/strong>. Defensores de Belgrano se encuentra puntero en su zona con 10 puntos junto a Col\u00f3n de Santa Fe.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/mMiejrfbO9k?si=eGAWqyn0oPOv5ijr\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Lleva ya <strong>281 minutos disputados y siempre integrando el 11 inicial<\/strong>. Cabe recordar que sali\u00f3 <strong>a pr\u00e9stamo por un a\u00f1o, sin cargo y sin opci\u00f3n<\/strong>, y deber\u00e1 volver al Rojo a principios del 2025.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>David Sayago lleva 2 tantos convertidos en 4 partidos con la camiseta de Defensores de Belgrano. El delantero, que todav\u00eda pertenece a Independiente, fue al Drag\u00f3n a buscar los minutos que no iba a tener en el Rojo. Por suerte los est\u00e1 logrando y se dio el lujo de poder marcar. Su mejor versi\u00f3n la [&hellip;]<\/p>\n","protected":false},"author":101036,"featured_media":117857,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3297,3247],"tags":[153,4796,3734],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/117856"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/101036"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=117856"}],"version-history":[{"count":1,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/117856\/revisions"}],"predecessor-version":[{"id":117858,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/117856\/revisions\/117858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/117857"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=117856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=117856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=117856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}