{"id":118621,"date":"2024-04-18T21:34:10","date_gmt":"2024-04-19T00:34:10","guid":{"rendered":"https:\/\/www.locoxelrojo.com\/independiente\/?p=118621"},"modified":"2024-04-18T21:34:10","modified_gmt":"2024-04-19T00:34:10","slug":"hay-rival-para-los-16avos-de-la-copa-argentina","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2024\/04\/18\/hay-rival-para-los-16avos-de-la-copa-argentina\/","title":{"rendered":"Hay rival para los 16avos de la Copa Argentina"},"content":{"rendered":"<p><strong>Juventud Unida de San Luis pas\u00f3 a los 16avos de final de la Copa Argentina y ser\u00e1 el pr\u00f3ximo rival de Independiente.<\/strong><\/p>\n<p>Despu\u00e9s de la victoria 3-0 ante Deportivo Laferrere en el debut, el Rojo estaba a la espera de conocer al adversario para la siguiente instancia. El mismo sal\u00eda del partido entre <strong>Deportivo Maip\u00fa<\/strong> (donde juega Patricio Ostachuk) y <strong>Juventud Unida<\/strong>.<\/p>\n<p>Este jueves, los mendocinos y los puntanos se vieron las caras y empataron 1-1 en C\u00f3rdoba, por lo que la definici\u00f3n se estir\u00f3 a los penales. All\u00ed, <strong>el Aurizaul se impuso 8-7 y pas\u00f3 a los 16avos, donde se ver\u00e1 las caras con el Rey de Copas<\/strong>.<\/p>\n<p><strong>Juventud Unida juega en el Torneo Federal A<\/strong>, donde marcha 2\u00ba en su zona tras cuatro fechas disputadas. Todav\u00eda no hay fecha ni horario ni estadio confirmado para el partido con Independiente.<\/p>\n<h3>As\u00ed se clasific\u00f3 Juventud Unida<\/h3>\n<p><iframe loading=\"lazy\" title=\"32avos: Deportivo Maip\u00fa 1 (7) - Juventud Unida 1 (8)\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/wBL3pTqN0z8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juventud Unida de San Luis pas\u00f3 a los 16avos de final de la Copa Argentina y ser\u00e1 el pr\u00f3ximo rival de Independiente. Despu\u00e9s de la victoria 3-0 ante Deportivo Laferrere en el debut, el Rojo estaba a la espera de conocer al adversario para la siguiente instancia. El mismo sal\u00eda del partido entre Deportivo Maip\u00fa [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":118624,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[800,3247],"tags":[153,5559,3138],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/118621"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=118621"}],"version-history":[{"count":2,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/118621\/revisions"}],"predecessor-version":[{"id":118625,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/118621\/revisions\/118625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/118624"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=118621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=118621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=118621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}