{"id":128113,"date":"2025-12-24T18:38:44","date_gmt":"2025-12-24T21:38:44","guid":{"rendered":"https:\/\/www.locoxelrojo.com\/independiente\/?p=128113"},"modified":"2025-12-24T18:38:44","modified_gmt":"2025-12-24T21:38:44","slug":"va-a-jugar-en-tigre","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2025\/12\/24\/va-a-jugar-en-tigre\/","title":{"rendered":"\u00bfVa a jugar en Tigre?"},"content":{"rendered":"<p><strong>Santiago L\u00f3pez tiene chances de salir a jugar nuevamente a pr\u00e9stamo: su destino ser\u00eda Tigre.<\/strong><\/p>\n<p>Al delantero de 19 a\u00f1os se le termina su cesi\u00f3n en Rosario Central. <strong>El Canalla no hizo uso de la opci\u00f3n de compra<\/strong> y debe regresar a Independiente. Sin embargo, no se quedar\u00eda en el Rojo.<\/p>\n<p><strong>El Rojo tiene acordado con Tigre un pr\u00e9stamo por un a\u00f1o, con opci\u00f3n a extender por 6 meses m\u00e1s, con cargo y una opci\u00f3n de compra de 2.000.000 de d\u00f3lares por el 70% del pase.<\/strong><\/p>\n<p>Antes de cerrarse la operaci\u00f3n con el Matador de Victoria, <strong>L\u00f3pez tendr\u00e1 que acordar un nuevo contrato con Independiente<\/strong>, ya que su v\u00ednculo con el Rey de Copas finaliza el 31 de diciembre 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago L\u00f3pez tiene chances de salir a jugar nuevamente a pr\u00e9stamo: su destino ser\u00eda Tigre. Al delantero de 19 a\u00f1os se le termina su cesi\u00f3n en Rosario Central. El Canalla no hizo uso de la opci\u00f3n de compra y debe regresar a Independiente. Sin embargo, no se quedar\u00eda en el Rojo. El Rojo tiene acordado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":120724,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3280,3247],"tags":[153,5162,309],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/128113"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=128113"}],"version-history":[{"count":1,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/128113\/revisions"}],"predecessor-version":[{"id":128114,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/128113\/revisions\/128114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/120724"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=128113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=128113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=128113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}