{"id":128122,"date":"2025-12-26T17:09:48","date_gmt":"2025-12-26T20:09:48","guid":{"rendered":"https:\/\/www.locoxelrojo.com\/independiente\/?p=128122"},"modified":"2025-12-26T17:09:48","modified_gmt":"2025-12-26T20:09:48","slug":"el-chaco-cambia-de-rumbo","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2025\/12\/26\/el-chaco-cambia-de-rumbo\/","title":{"rendered":"\u00bfEl Chaco cambia de rumbo?"},"content":{"rendered":"<p><strong>Braian Mart\u00ednez puede continuar su carrera en el exterior. <\/strong><\/p>\n<p>El mercado de pases est\u00e1 tomando envi\u00f3n y uno que va a cambiar de destino es el Chaco Mart\u00ednez. <strong>Actualmente est\u00e1 a pr\u00e9stamo en Tigre, pero como Independiente tiene una opci\u00f3n de repesca antes del 31 de diciembre har\u00e1 uso de ella.<\/strong><\/p>\n<p>\u00bfCu\u00e1l es el motivo? No es porque Gustavo Quinteros quiere contar con \u00e9l. <strong>Es para irse al Everton de Chile<\/strong>, club que conoce muy bien y ya tuvo un buen paso en el 2024, que se vi interrumpido por cuando sufri\u00f3 una rotura de ligamentos que lo margin\u00f3 de las canchas casi 8 meses.<\/p>\n<p>La dirigencia est\u00e1 negociando su salida, que ser\u00e1 nuevamente <strong>a pr\u00e9stamo por 12 meses y con una opci\u00f3n de compra que a\u00fan no est\u00e1 definida.<\/strong><\/p>\n<p>Durante su estad\u00eda en el Matador de Victoria <strong>jug\u00f3 15 partidos, convirti\u00f3 2 goles, 1 asistencia en 486 minutos en cancha.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Braian Mart\u00ednez puede continuar su carrera en el exterior. El mercado de pases est\u00e1 tomando envi\u00f3n y uno que va a cambiar de destino es el Chaco Mart\u00ednez. Actualmente est\u00e1 a pr\u00e9stamo en Tigre, pero como Independiente tiene una opci\u00f3n de repesca antes del 31 de diciembre har\u00e1 uso de ella. \u00bfCu\u00e1l es el motivo? [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":128123,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3297,3247],"tags":[4452,153,5460,309],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/128122"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=128122"}],"version-history":[{"count":1,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/128122\/revisions"}],"predecessor-version":[{"id":128124,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/128122\/revisions\/128124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/128123"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=128122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=128122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=128122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}