{"id":129414,"date":"2026-03-28T18:47:22","date_gmt":"2026-03-28T21:47:22","guid":{"rendered":"https:\/\/www.locoxelrojo.com\/independiente\/?p=129414"},"modified":"2026-03-28T20:03:49","modified_gmt":"2026-03-28T23:03:49","slug":"se-corto-la-racha-de-146-partidos-de-rey","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2026\/03\/28\/se-corto-la-racha-de-146-partidos-de-rey\/","title":{"rendered":"Se cort\u00f3 la racha de 146 partidos de Rey"},"content":{"rendered":"<p><strong>Con la titularidad de Joaqu\u00edn Bl\u00e1zquez en el triunfo 4-2 de Independiente sobre Atenas de R\u00edo Cuarto, se cort\u00f3 la hist\u00f3rica marca de Rodrigo Rey.<\/strong><\/p>\n<p>Una de las aristas que dej\u00f3 la victoria del Rojo fue, sin dudas, la salida del capit\u00e1n en la tarde de Florencio Varela. El ex Talleres reemplaz\u00f3 a Rey y recibi\u00f3 2 goles, ambos sobre el final y sin responsabilidad alguna.<strong> Ante esto, la racha de 146 partidos consecutivos como titular en el arco del Rey de Copas lleg\u00f3 a su fin.<\/strong><\/p>\n<p><strong>Independiente no ten\u00eda a Rodrigo Rey desde el arranque de los 90 minutos desde el 23 de octubre de 2022.<\/strong> Aquella tarde, el equipo en ese entonces de Julio Falcioni visit\u00f3 a Boca en La Bombonera, igual\u00f3 2-2 y el arquero fue Milton \u00c1lvarez. Ese partido es recordado por la dram\u00e1tica definici\u00f3n de campeonato donde Racing no pudo salir campe\u00f3n al enfrentarse a River en el Cilindro.<\/p>\n<p>El ex Gimnasia La Plata debut\u00f3 con el buzo del Rojo el 23 de enero de 2023, en el triunfo 1-0 frente a Talleres en C\u00f3rdoba.<strong> En el camino de estos 146 encuentros consecutivos, el 8 de abril de 2025 super\u00f3 a Carlos Goy\u00e9n con el r\u00e9cord de presencias al hilo<\/strong> (102 entre 1981 y 1983) frente a Boston River por la Copa Sudamericana (fue victoria 2-1).<strong> En total, recibi\u00f3 123 goles y mantuvo la valla invicta en 64 oportunidades, en 13.140 minutos.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la titularidad de Joaqu\u00edn Bl\u00e1zquez en el triunfo 4-2 de Independiente sobre Atenas de R\u00edo Cuarto, se cort\u00f3 la hist\u00f3rica marca de Rodrigo Rey. Una de las aristas que dej\u00f3 la victoria del Rojo fue, sin dudas, la salida del capit\u00e1n en la tarde de Florencio Varela. El ex Talleres reemplaz\u00f3 a Rey y [&hellip;]<\/p>\n","protected":false},"author":101038,"featured_media":128967,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1989,3247],"tags":[5916,153,3273,1808,5319],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/129414"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/101038"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=129414"}],"version-history":[{"count":1,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/129414\/revisions"}],"predecessor-version":[{"id":129415,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/129414\/revisions\/129415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/128967"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=129414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=129414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=129414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}