{"id":15186,"date":"2012-02-19T23:38:40","date_gmt":"2012-02-20T02:38:40","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=15186"},"modified":"2015-09-22T22:53:51","modified_gmt":"2015-09-23T01:53:51","slug":"%e2%80%9csiempre-es-exclusivamente-responsabilidad-del-entrenador%e2%80%9d","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2012\/02\/19\/%e2%80%9csiempre-es-exclusivamente-responsabilidad-del-entrenador%e2%80%9d\/","title":{"rendered":"Ram\u00f3n D\u00edaz: &#8220;Siempre es responsabilidad del entrenador&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.locoxelrojo.com.ar\/independiente\/wp-content\/uploads\/2012\/02\/ramon-cai.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-15187\" title=\"ramon-cai\" src=\"http:\/\/www.locoxelrojo.com.ar\/independiente\/wp-content\/uploads\/2012\/02\/ramon-cai.jpg\" alt=\"\" width=\"590\" height=\"315\" srcset=\"https:\/\/locoxelrojo.com\/independiente\/wp-content\/uploads\/2012\/02\/ramon-cai.jpg 590w, https:\/\/locoxelrojo.com\/independiente\/wp-content\/uploads\/2012\/02\/ramon-cai-300x160.jpg 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/><\/a><\/p>\n<p>Al t\u00e9rmino del partido, el t\u00e9cnico de Independiente se mostr\u00f3 muy molesto por la derrota ante Lan\u00fas y reconoci\u00f3 los errores propios durante el partido. <strong>\u201cSiempre es exclusivamente responsabilidad del entrenador. Le pido a la gente que no se la agarre con los jugadores porque ellos no son; al contrario, creo que est\u00e1n entregando todo\u201d<\/strong>, remarc\u00f3 Ram\u00f3n D\u00edaz en conferencia de prensa.<\/p>\n<p><strong>\u201cMe voy con bronca, porque con el esfuerzo que est\u00e1n haciendo los jugadores no podemos conseguir lo que queremos nosotros. Tuvieron una entrega enorme, el equipo est\u00e1 entregando todo lo que tiene, por eso les dije que se queden tranquilos\u201d<\/strong>, manifest\u00f3 el DT, quien se lament\u00f3 por las ocasiones de gol desperdiciadas: <strong>\u201cNo estuvimos tan precisos en las chances que tuvimos, porque sino todo hubiera cambiado. Tuvimos algunas con el Tecla(Far\u00edas). No muchas, pero las tuvimos\u201d<\/strong>.<\/p>\n<p>Por otra parte, Ram\u00f3n D\u00edaz reflexion\u00f3 sobre el rendimiento del equipo y asegur\u00f3 que pueden mejorarlo en los pr\u00f3ximos partidos: <strong>\u201cTodos tenemos que mantener la tranquilidad, analizar bien qu\u00e9 est\u00e1 pasando y d\u00f3nde estamos fallando, porque tenemos un equipo que tiene que jugar mejor. Los primeros 15 \u00f3 20 minutos estuvimos en dificultad, despu\u00e9s se pudieron acomodar\u201d<\/strong>. Adem\u00e1s, consider\u00f3 que <strong>\u201cel equipo tiene que mantener m\u00e1s el equilibrio en la mitad de la cancha\u201d<\/strong>.<\/p>\n<p>Sobre los insultos de la gente al t\u00e9rmino del partido, Ram\u00f3n opin\u00f3: <strong>\u201cEntiendo a la gente, porque nosotros hab\u00edamos trabajado much\u00edsimo en la pretemporada para tener un buen arranque. Hicimos grandes sacrificios, los hizo el grupo y los hicimos todos, y no conseguimos los resultados. Somos los primeros que queremos conseguir los resultados para la gente\u201d<\/strong>. Finalmente, agreg\u00f3: <strong>\u201cMe gust\u00f3 el apoyo del inicio. Necesitamos a la gente porque sin ellos es muy complicado todo. Los jugadores necesitan tranquilidad\u201d<\/strong>.<\/p>\n<p>A la hora de analizar a los jugadores, el DT elogi\u00f3 a Walter Busse, uno de los puntos m\u00e1s altos de la tarde: <strong>\u201cMe gust\u00f3 mucho. En el primer tiempo tir\u00f3 cuatro o cinco centros con los que podr\u00edamos haber convertido el gol. En el segundo tiempo, por ah\u00ed a lo \u00faltimo ya se cans\u00f3\u201d<\/strong>. A su vez, opin\u00f3 sobre Patricio Rodr\u00edguez: <strong>\u201cTuvo buenos arranques, pero creo que le falta m\u00e1s continuidad. El cambio fue t\u00e1ctico, lo saqu\u00e9 yo\u201d<\/strong>.<\/p>\n<p>El entrenador tambi\u00e9n se refiri\u00f3 al nuevo esquema t\u00e1ctico utilizado en el partido, con l\u00ednea de tres defensores: <strong>\u201cMe gust\u00f3, por momentos presionamos bien, por momentos cometimos errores. Al final ya terminaba todo en empate, pero ten\u00e9s esta clase de jugadores que en cualquier momento te desequilibran, y nos convierten ese gol inesperado en un achique\u201d<\/strong>.<\/p>\n<p>Finalmente, Ram\u00f3n D\u00edaz reconoci\u00f3 la falta de gol del equipo y asegur\u00f3 que har\u00e1 todo lo posible para conseguir resultados: <strong>\u201cNo nos vamos conformes porque la gente espera otra cosa y nosotros tambi\u00e9n. Vamos a trabajar, tenemos que salir de estas situaciones, porque no puede ser que en varios partidos no podamos convertir un gol, y m\u00e1s siendo nosotros los atacantes\u201d<\/strong>. En tanto, remarc\u00f3 que no piensa en renunciar como director t\u00e9cnico: <strong>\u201cNo me pongo plazos. El f\u00fatbol es as\u00ed\u201d<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al t\u00e9rmino del partido, el t\u00e9cnico de Independiente se mostr\u00f3 muy molesto por la derrota ante Lan\u00fas y reconoci\u00f3 los errores propios durante el partido. \u201cSiempre es exclusivamente responsabilidad del entrenador. Le pido a la gente que no se la agarre con los jugadores porque ellos no son; al contrario, creo que est\u00e1n entregando todo\u201d, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[153,500],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/15186"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=15186"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/15186\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=15186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=15186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=15186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}