{"id":15257,"date":"2012-02-21T19:02:44","date_gmt":"2012-02-21T22:02:44","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=15257"},"modified":"2012-02-21T19:02:44","modified_gmt":"2012-02-21T22:02:44","slug":"parra-asumo-que-nos-insultan-por-decantacion","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2012\/02\/21\/parra-asumo-que-nos-insultan-por-decantacion\/","title":{"rendered":"Parra: &#8220;Asumo que nos insultan por decantaci\u00f3n&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.locoxelrojo.com.ar\/independiente\/wp-content\/uploads\/2012\/02\/4.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-15258\" title=\"4\" src=\"http:\/\/www.locoxelrojo.com.ar\/independiente\/wp-content\/uploads\/2012\/02\/4.jpg\" alt=\"\" width=\"590\" height=\"315\" srcset=\"https:\/\/locoxelrojo.com\/independiente\/wp-content\/uploads\/2012\/02\/4.jpg 590w, https:\/\/locoxelrojo.com\/independiente\/wp-content\/uploads\/2012\/02\/4-300x160.jpg 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/><\/a><\/p>\n<p>El delantero de Independiente, Facundo Parra, dialog\u00f3 esta tarde en La Red y manifest\u00f3 que la gente los insulta por decantaci\u00f3n. Y agreg\u00f3: <strong>&#8220;No puedo cambiar una situaci\u00f3n de la cual no tengo formas&#8221;<\/strong>. Tambi\u00e9n se refiri\u00f3 a Ram\u00f3n D\u00edaz, al rendimiento del equipo y a la barra brava.<\/p>\n<p>Los insultos y la silbatina tras el partido contra Lan\u00fas trajo cola. \u00a0Y Parra fue claro: <strong>&#8220;Aumo que nos insultan por decantaci\u00f3n. No puedo cambiar una situaci\u00f3n de la cual no tengo formas&#8221;<\/strong>. <strong>&#8220;Igualmente es entendible porque no rendimos contra San Mart\u00edn y si bien mejoramos, no dimos lo que el hincha busca ante Lan\u00fas. Asumimos las responsabilidades&#8221;<\/strong>, agreg\u00f3.<\/p>\n<p>Respecto del entrenador, reconoci\u00f3 que tiene trayectoria como para levantar esto:<strong> &#8220;No se puede negar que Ram\u00f3n gan\u00f3 mucho, yo veo el laburo del d\u00eda a d\u00eda y es bueno. El f\u00fatbol es resultadista&#8221;<\/strong>. Y sigui\u00f3: <strong>&#8220;El jugador tiene que respetar al t\u00e9cnico y tratar de dar lo mejor m\u00e1s all\u00e1 de lo que te guste o no&#8221;<\/strong>.<\/p>\n<p>Por otro lado marc\u00f3 la clara falta de ocasiones de gol del equipo y manifest\u00f3 que <strong>&#8220;no se logra crear peligro ni sostener la pelota&#8221;<\/strong>. <strong>&#8220;Algo pasa y es claro, no depende del gol o la picard\u00eda. El juego es en conjunto y no se genera&#8221;<\/strong>, sentenci\u00f3.<\/p>\n<p>Tambi\u00e9n cont\u00f3 que la barra brava le hizo un pedido a los jugadores: <strong>&#8220;Me enter\u00e9 que la barra quer\u00eda camisetas, pero es parte de lo normal. \u00bfC\u00f3mo cambiamos la inseguridad del pa\u00eds? Hay que tratar de evitar el problema&#8221;<\/strong>.<\/p>\n<p>Finalmente se quej\u00f3 por los penales no cobrados en las dos fechas disputadas:<strong> &#8220;Vamos a tener que hablar con los \u00e1rbitros para que nos den una mano. Son 3 en 2 partidos.Voy a llamar a quien dirija&#8221;<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El delantero de Independiente, Facundo Parra, dialog\u00f3 esta tarde en La Red y manifest\u00f3 que la gente los insulta por decantaci\u00f3n. Y agreg\u00f3: &#8220;No puedo cambiar una situaci\u00f3n de la cual no tengo formas&#8221;. Tambi\u00e9n se refiri\u00f3 a Ram\u00f3n D\u00edaz, al rendimiento del equipo y a la barra brava. Los insultos y la silbatina tras [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[153,36,500],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/15257"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=15257"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/15257\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=15257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=15257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=15257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}