{"id":15265,"date":"2012-02-22T15:38:26","date_gmt":"2012-02-22T18:38:26","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=15265"},"modified":"2012-02-22T15:39:49","modified_gmt":"2012-02-22T18:39:49","slug":"%c2%bfse-vienen-mas-cambios","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2012\/02\/22\/%c2%bfse-vienen-mas-cambios\/","title":{"rendered":"\u00bfSe vienen m\u00e1s cambios?"},"content":{"rendered":"<p><a href=\"http:\/\/www.locoxelrojo.com.ar\/independiente\/wp-content\/uploads\/2012\/02\/entrenamiento04.jpg\"><img loading=\"lazy\" src=\"http:\/\/www.locoxelrojo.com.ar\/independiente\/wp-content\/uploads\/2012\/02\/entrenamiento04.jpg\" alt=\"\" title=\"entrenamiento04\" width=\"590\" height=\"315\" class=\"alignnone size-full wp-image-15266\" srcset=\"https:\/\/locoxelrojo.com\/independiente\/wp-content\/uploads\/2012\/02\/entrenamiento04.jpg 590w, https:\/\/locoxelrojo.com\/independiente\/wp-content\/uploads\/2012\/02\/entrenamiento04-300x160.jpg 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/><\/a><\/p>\n<p>Independiente volvi\u00f3 a entrenarse esta ma\u00f1ana en Villa Dom\u00ednico pensando en el partido del pr\u00f3ximo s\u00e1bado ante Estudiantes y todo parece indicar que Ram\u00f3n D\u00edaz introducir\u00e1 m\u00e1s cambios. Las principales novedades de la ma\u00f1ana pasaron por la vuelta de Roberto Batti\u00f3n al equipo titular y la salida de Patricio Rodr\u00edguez y Fernando Godoy, quienes jugaron para los suplentes en un partido informal de 30 minutos.<\/p>\n<p>Los titulares formaron con: <strong>Hilario Navarro; Eduardo Tuzzio, Juli\u00e1n Velazquez, Gabriel Milito; Walter Busse, Roberto Batti\u00f3n, Iv\u00e1n P\u00e9rez, Osmar Ferreyra; Mat\u00edas Defederico; Facundo Parra, Ernesto Far\u00edas.<\/strong><\/p>\n<p>En tanto, para los suplentes jugaron: Adri\u00e1n Gabbarini; Gabriel Vall\u00e9s, Carlos Matheu, Leonel Galeano, Lucas Kruspzky; Lucas Villaf\u00e1\u00f1ez, Nicol\u00e1s Delmonte, Fernando Godoy, Patricio Rodr\u00edguez; Patricio Vidal y Mart\u00edn Ben\u00edtez.<\/p>\n<p><strong>El partido termin\u00f3 1 a 0 a favor del equipo alternativo, con gol de Lucas Villaf\u00e1\u00f1ez. Ram\u00f3n D\u00edaz mantuvo el esquema 3-4-1-2 en la alineaci\u00f3n titular, en la que Mat\u00edas Defederico se desempe\u00f1\u00f3 como enganche.<\/strong><\/p>\n<p>Por otra parte, Hern\u00e1n Fredes, Cristian Pellerano y Fabi\u00e1n Monserrat entrenaron de forma diferenciada para recuperarse de sus respectivas lesiones. <\/p>\n<p><strong>Adem\u00e1s, Ram\u00f3n decidi\u00f3 que algunos jugadores entrenen con la Reserva: Diego Rodr\u00edguez, Javier B\u00e1ez, Adri\u00e1n Argach\u00e1, Francisco Pizzini, Brian Nieva y Leonel N\u00fa\u00f1ez.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Independiente volvi\u00f3 a entrenarse esta ma\u00f1ana en Villa Dom\u00ednico pensando en el partido del pr\u00f3ximo s\u00e1bado ante Estudiantes y todo parece indicar que Ram\u00f3n D\u00edaz introducir\u00e1 m\u00e1s cambios. Las principales novedades de la ma\u00f1ana pasaron por la vuelta de Roberto Batti\u00f3n al equipo titular y la salida de Patricio Rodr\u00edguez y Fernando Godoy, quienes jugaron [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[29,71,187,379,41,31],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/15265"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=15265"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/15265\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=15265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=15265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=15265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}