{"id":15525,"date":"2012-03-01T21:06:23","date_gmt":"2012-03-02T00:06:23","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=15525"},"modified":"2012-03-01T21:06:23","modified_gmt":"2012-03-02T00:06:23","slug":"galeano-no-salir-mas-del-equipo","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2012\/03\/01\/galeano-no-salir-mas-del-equipo\/","title":{"rendered":"Galeano: &#8220;No salir m\u00e1s del equipo&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.locoxelrojo.com.ar\/independiente\/wp-content\/uploads\/2012\/03\/leonel_Galeano.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-15526\" title=\"leonel_Galeano\" src=\"http:\/\/www.locoxelrojo.com.ar\/independiente\/wp-content\/uploads\/2012\/03\/leonel_Galeano.jpg\" alt=\"\" width=\"590\" height=\"315\" srcset=\"https:\/\/locoxelrojo.com\/independiente\/wp-content\/uploads\/2012\/03\/leonel_Galeano.jpg 590w, https:\/\/locoxelrojo.com\/independiente\/wp-content\/uploads\/2012\/03\/leonel_Galeano-300x160.jpg 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/><\/a><\/p>\n<p><strong>Leonel Galeano<\/strong> manifest\u00f3 su deseo de no dejar el primer equipo en su vuelta a los titulares del plantel profesional. <strong>&#8220;Espero aprovechar la oportunidad y no salir m\u00e1s del equipo<\/strong>&#8220;, asegur\u00f3 en di\u00e1logo con Radio La Red. Luego advirti\u00f3: &#8220;no podemos dejar m\u00e1s puntos en el camino&#8221;.<\/p>\n<p><strong>&#8220;Espero que sea el punto de partido, ambos equipos venimos golpeados. Hay que pegar primero porque metiendo el gol de entrada se facilitan las cosas. Tenemos que jugar con el coraz\u00f3n<\/strong>&#8220;, entendi\u00f3 sobre lo que ser\u00e1 el tr\u00e1mite del partido frente a Argentinos Juniors el pr\u00f3ximo s\u00e1bado a las 19 en el Libertadores de Am\u00e9rica.<\/p>\n<p>Leonel Galeano tiene <strong>77 partidos en la primera divisi\u00f3n de Independiente y 6 goles <\/strong>-62 por campeonato y 15 por copas-. Debut\u00f3 un 21\/8 de 2009 y fue expulsado en 3 oportunidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leonel Galeano manifest\u00f3 su deseo de no dejar el primer equipo en su vuelta a los titulares del plantel profesional. &#8220;Espero aprovechar la oportunidad y no salir m\u00e1s del equipo&#8220;, asegur\u00f3 en di\u00e1logo con Radio La Red. Luego advirti\u00f3: &#8220;no podemos dejar m\u00e1s puntos en el camino&#8221;. &#8220;Espero que sea el punto de partido, ambos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[473,1256,153,173,32,60,500,1255],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/15525"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=15525"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/15525\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=15525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=15525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=15525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}