{"id":19161,"date":"2012-07-09T00:24:42","date_gmt":"2012-07-09T03:24:42","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=19161"},"modified":"2012-07-09T00:41:54","modified_gmt":"2012-07-09T03:41:54","slug":"c-diaz-en-este-momento-tengo-la-piel-de-gallina","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2012\/07\/09\/c-diaz-en-este-momento-tengo-la-piel-de-gallina\/","title":{"rendered":"C. D\u00edaz: &#8220;En este momento tengo la piel de gallina&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.locoxelrojo.com.ar\/independiente\/wp-content\/uploads\/2012\/07\/Cristian_D\u00edaz.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-19162\" title=\"Cristian_D\u00edaz\" src=\"http:\/\/www.locoxelrojo.com.ar\/independiente\/wp-content\/uploads\/2012\/07\/Cristian_D\u00edaz.jpg\" alt=\"\" width=\"590\" height=\"315\" srcset=\"https:\/\/locoxelrojo.com\/independiente\/wp-content\/uploads\/2012\/07\/Cristian_D\u00edaz.jpg 590w, https:\/\/locoxelrojo.com\/independiente\/wp-content\/uploads\/2012\/07\/Cristian_D\u00edaz-300x160.jpg 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/><\/a><\/p>\n<p>Cristian D\u00edaz habl\u00f3 esta noche en Correo Independiente y <strong>se mostr\u00f3 emocionado por los refuerzos: &#8220;En este momento tengo la piel de gallina&#8221;. Adem\u00e1s, elogi\u00f3 a la dirigencia y le envi\u00f3 un mensaje a los hinchas.<\/strong><\/p>\n<p>Los nombres que suenan y que cada vez est\u00e1n m\u00e1s cerca motivan. El entrenador lo sabe y lo siente. <strong>&#8220;En este momento tengo la piel de gallina. Me saco el sombrero ante esta dirigencia que est\u00e1 haciendo un esfuerzo descomunal para traer los refuerzos necesarios&#8221;<\/strong>, expres\u00f3.<\/p>\n<p>Tambi\u00e9n se refiri\u00f3 al caso particular de Mario Bolatti: <strong>&#8220;Esperemos que pronto llegue para firmar. Lo necesitamos&#8221;.<\/strong><\/p>\n<p><strong>&#8220;Seguramente va a llegar un delantero a Independiente que sea socio de Far\u00edas. Vidal es una opci\u00f3n buena, pero no es una temporada para \u00e9l por las cosas que se juegan. Los grandes tienen que llevar el peso&#8221;<\/strong>, sostuvo en cuanto a la parte ofensiva.<\/p>\n<p>Sobre lo que espera del equipo en el futuro cercano fue claro: <strong>&#8220;Buscaremos un equipo s\u00f3lido, que reciba menos goles de los que marquemos&#8221;<\/strong>. Y le dej\u00f3 un mensaje a la gente: <strong>&#8220;Esperemos que el hincha aliente los 90 minutos&#8217;. El equipo va a generar ilusiones. Necesitamos que llenen todas las tribunas&#8221;.<\/strong><\/p>\n<p>Por otro lado, habl\u00f3 de los jugadores que volvieron y tendr\u00e1 en cuenta: <strong>&#8220;C\u00e1ceres no solo jug\u00f3, si no que Chicago termin\u00f3 ascendiendo. Tiene mucho m\u00e1s rodaje que un jugador de reserva. Respecto de Mancuello, no hay muchos volantes zurdos, esperemos explotarlo&#8221;.<\/strong><\/p>\n<p><strong>&#8220;Me gustar\u00eda quedarme ac\u00e1. Yo no estoy por la plata. Sigo cobrando lo mismo que en reserva. Capaz que este puesto era para otra persona que no agarr\u00f3 por la plata&#8221;<\/strong>, cerr\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cristian D\u00edaz habl\u00f3 esta noche en Correo Independiente y se mostr\u00f3 emocionado por los refuerzos: &#8220;En este momento tengo la piel de gallina&#8221;. Adem\u00e1s, elogi\u00f3 a la dirigencia y le envi\u00f3 un mensaje a los hinchas. Los nombres que suenan y que cada vez est\u00e1n m\u00e1s cerca motivan. El entrenador lo sabe y lo siente. [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[153,188,946,1508,98,192,1561],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/19161"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=19161"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/19161\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=19161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=19161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=19161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}