{"id":34041,"date":"2013-07-07T18:10:42","date_gmt":"2013-07-07T21:10:42","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=34041"},"modified":"2013-07-07T19:24:29","modified_gmt":"2013-07-07T22:24:29","slug":"bellocq-y-pereira-se-van-de-pretemporada","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2013\/07\/07\/bellocq-y-pereira-se-van-de-pretemporada\/","title":{"rendered":"Bellocq y Pereira se van de pretemporada"},"content":{"rendered":"<p><strong>Franco Bellocq y Guillermo Pereira son los dos jugadores de la Reserva del Club Atl\u00e9tico Independiente que por primera vez realizar\u00e1n la pretemporada con el plantel de Primera Divisi\u00f3n.<\/strong><\/p>\n<p>Sus destacadas actuaciones en &#8220;La Piponeta&#8221; llamaron la atenci\u00f3n de Miguel Brindisi, quien ante la falta de refuerzos y las pocas variantes con las que cuenta en el plantel, se vio obligado a poner el ojo en los pibes del club.<\/p>\n<p><strong>Franco Bellocq es categor\u00eda 93 y lleg\u00f3 a Independiente en el a\u00f1o 2007. Es oriundo de General Lavalle, C\u00f3rdoba y su puesto original es volante central.<\/strong> Ariel Wiktor, entrenador de la Reserva lo tuvo muy en cuenta en los \u00faltimos meses y se convirti\u00f3 en una pieza clave para &#8220;La Piponeta&#8221;. El volante de 19 a\u00f1os, junto a Marcelo Vidal, son las \u00fanicas alternativas que tiene Brindisi, hoy por hoy, al puesto que dejaron vacante Fabi\u00e1n Vargas y Fernando Godoy.<\/p>\n<p><strong>Guillermo Pereira es categor\u00eda 94 y arrib\u00f3 al club en el a\u00f1o 2009. Es oriundo de Pergamino, Buenos Aires y durante la temporada pasada fue uno de los volantes de &#8220;La Piponeta&#8221;.<\/strong> En el \u00faltimo semestre tuvo mayor continuidad en Reserva y hasta se dio el lujo de convertir algunos goles. Con 19 a\u00f1os, tendr\u00e1 su chance de mostrarse y ganarse la confianza del entrenador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Franco Bellocq y Guillermo Pereira son los dos jugadores de la Reserva del Club Atl\u00e9tico Independiente que por primera vez realizar\u00e1n la pretemporada con el plantel de Primera Divisi\u00f3n. Sus destacadas actuaciones en &#8220;La Piponeta&#8221; llamaron la atenci\u00f3n de Miguel Brindisi, quien ante la falta de refuerzos y las pocas variantes con las que cuenta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[2232,1638,2204],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/34041"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=34041"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/34041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/34047"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=34041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=34041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=34041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}