{"id":34141,"date":"2013-07-10T13:43:00","date_gmt":"2013-07-10T16:43:00","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=34141"},"modified":"2015-10-07T22:31:40","modified_gmt":"2015-10-08T01:31:40","slug":"el-presidente-de-velez-confirma-el-acuerdo-por-razzotti","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2013\/07\/10\/el-presidente-de-velez-confirma-el-acuerdo-por-razzotti\/","title":{"rendered":"El Presidente de V\u00e9lez confirm\u00f3 el acuerdo por Razzotti"},"content":{"rendered":"<p><strong>Miguel Calello,\u00a0<strong>Presidente de V\u00e9lez Sarsfield,<\/strong>\u00a0confirm\u00f3 este mediod\u00eda la salida de Franco Razzotti. El volante ser\u00e1 jugador de Independiente en las pr\u00f3ximas horas y llegar\u00e1 a pr\u00e9stamo por un a\u00f1o con cargo y con opci\u00f3n de compra.<\/strong><\/p>\n<p><strong>&#8220;Hablamos mucho con Franco (Razzotti). \u00c9l busca otros desaf\u00edos y hay muchos en su puesto. Lo entendimos y jugar\u00e1 en Independiente&#8221;<\/strong>, fueron las palabras de Calello en Radio Cooperativa. <strong>&#8220;La operaci\u00f3n por es a pr\u00e9stamo, con cargo y con opci\u00f3n&#8221;<\/strong>, agreg\u00f3.<\/p>\n<p>Como ya adelantamos en LocoXelRojo, desde el lunes se viene trabajando en la salida de Razzotti de V\u00e9lez. <strong>Primero tuvo que solucionar algunos problemas contractuales en el club de Liniers. Luego, recibi\u00f3 el visto bueno de Ricardo Gareca y tambi\u00e9n el del Manager Christian Bassedas. Adem\u00e1s del acuerdo entre Javier Cantero y Calello, existi\u00f3 un llamado de Miguel Brindisi, que le manifest\u00f3 al jugador sus ganas de contar con \u00e9l.<\/strong><\/p>\n<p><strong>En las pr\u00f3ximas horas se firmar\u00e1 el contrato a pr\u00e9stamo por un a\u00f1o con cargo y con opci\u00f3n.<\/strong> Todav\u00eda no hay cifras oficiales, pero la operaci\u00f3n ser\u00eda por 100.000 d\u00f3lares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miguel Calello,\u00a0Presidente de V\u00e9lez Sarsfield,\u00a0confirm\u00f3 este mediod\u00eda la salida de Franco Razzotti. El volante ser\u00e1 jugador de Independiente en las pr\u00f3ximas horas y llegar\u00e1 a pr\u00e9stamo por un a\u00f1o con cargo y con opci\u00f3n de compra. &#8220;Hablamos mucho con Franco (Razzotti). \u00c9l busca otros desaf\u00edos y hay muchos en su puesto. Lo entendimos y jugar\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[153,2235,1692,2722],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/34141"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=34141"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/34141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/34142"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=34141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=34141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=34141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}