{"id":35005,"date":"2013-08-08T18:18:52","date_gmt":"2013-08-08T21:18:52","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=35005"},"modified":"2013-08-08T18:18:52","modified_gmt":"2013-08-08T21:18:52","slug":"cambio-de-horario-vs-aldosivi","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2013\/08\/08\/cambio-de-horario-vs-aldosivi\/","title":{"rendered":"Cambio de horario vs. Aldosivi"},"content":{"rendered":"<p>El partido entre Independiente y Aldosivi, que se iba a jugar el s\u00e1bado 17 a las 20:15h en Avellaneda, cambi\u00f3 de horario. Finalmente, <strong>el encuentro por la tercera fecha de la B Nacional se jugar\u00e1 a las 16h.<\/strong><\/p>\n<p>LocoXelRojo se comunic\u00f3 con la Asociaci\u00f3n de F\u00fatbol Argentino y argumentaron <strong>que el cambio de hora se debe a &#8220;la seguridad&#8221; y a que las autoridades &#8220;no quieren que el partido termine de noche&#8221;.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El partido entre Independiente y Aldosivi, que se iba a jugar el s\u00e1bado 17 a las 20:15h en Avellaneda, cambi\u00f3 de horario. Finalmente, el encuentro por la tercera fecha de la B Nacional se jugar\u00e1 a las 16h. LocoXelRojo se comunic\u00f3 con la Asociaci\u00f3n de F\u00fatbol Argentino y argumentaron que el cambio de hora se [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":35006,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[516,153],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/35005"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=35005"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/35005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/35006"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=35005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=35005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=35005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}