{"id":36236,"date":"2013-09-12T14:33:22","date_gmt":"2013-09-12T17:33:22","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=36236"},"modified":"2013-09-12T18:24:28","modified_gmt":"2013-09-12T21:24:28","slug":"de-felippe-prepara-cambios","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2013\/09\/12\/de-felippe-prepara-cambios\/","title":{"rendered":"De Felippe prepara cambios"},"content":{"rendered":"<p><strong>Independiente realiz\u00f3 este jueves por la ma\u00f1ana la pr\u00e1ctica de f\u00fatbol y Omar De Felippe meti\u00f3 dos cambios en relaci\u00f3n al equipo que consigui\u00f3 vencer a Hurac\u00e1n en Parque Patricios: Fabi\u00e1n Monserrat y Facundo Parra ingresaron en lugar de Leonel Miranda y Cristian Men\u00e9ndez.<\/strong><\/p>\n<p>A pesar del mal tiempo y las amenazas de fuertes lluvias, el plantel de Independiente pudo realizar un ensayo formal de cara al pr\u00f3ximo partido ante Banfield. <strong>De Felippe qued\u00f3 conforme por el resultado ante Hurac\u00e1n, pero preocupado por rendimiento del equipo. Por eso, en busca del once ideal, el entrenador realiz\u00f3 dos modificaciones: Miranda le dej\u00f3 su lugar a Monserrat en la mitad de la cancha y Parra fue el acompa\u00f1ante de Daniel Montenegro en la delantera.<\/strong><\/p>\n<p>Los que par\u00f3 De Felippe: <strong>Diego Rodr\u00edguez; Gabriel Vall\u00e9s, Samuel C\u00e1ceres, Claudio Morel Rodr\u00edguez, Lucas Villalba; Fabi\u00e1n Monserrat, Mart\u00edn Zapata, Reinaldo Alderete, Federico Mancuello; Daniel Montenegro y Facundo Parra.<\/strong><\/p>\n<p><strong>Federico Mancuello evoluciona favorablemente del traumatismo en su pierna izquierda y, de no mediar ning\u00fan inconveniente, estar\u00e1 el s\u00e1bado en cancha.<\/strong> Por su parte, <strong>la tendinitis le sigue jugando una mala pasada a Cristian Tula y lo dej\u00f3 nuevamente afuera del partido.<\/strong><\/p>\n<p>Ma\u00f1ana viernes,<strong> a partir de las 9:30, el plantel realizar\u00e1 la \u00faltima pr\u00e1ctica en Dom\u00ednico, a puertas cerradas y sin atenci\u00f3n a la prensa.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Independiente realiz\u00f3 este jueves por la ma\u00f1ana la pr\u00e1ctica de f\u00fatbol y Omar De Felippe meti\u00f3 dos cambios en relaci\u00f3n al equipo que consigui\u00f3 vencer a Hurac\u00e1n en Parque Patricios: Fabi\u00e1n Monserrat y Facundo Parra ingresaron en lugar de Leonel Miranda y Cristian Men\u00e9ndez. A pesar del mal tiempo y las amenazas de fuertes lluvias, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[2236,26,984,36,1347,2032,172],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/36236"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=36236"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/36236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/36237"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=36236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=36236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=36236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}