{"id":36259,"date":"2013-09-12T20:00:33","date_gmt":"2013-09-12T23:00:33","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=36259"},"modified":"2013-09-12T20:00:33","modified_gmt":"2013-09-12T23:00:33","slug":"de-felippe-tiene-banca","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2013\/09\/12\/de-felippe-tiene-banca\/","title":{"rendered":"De Felippe tiene banca"},"content":{"rendered":"<p>LocoXelRojo realiz\u00f3 una encuesta <strong>para los hinchas de Independiente respecto de sus sensaciones en cuanto a la llegada de Omar De Felippe a Independiente. Los resultados fueron contundentes: el nuevo entrenador tiene banca de parte del hincha.<\/strong><\/p>\n<p><strong>&#8220;\u00bfEst\u00e1s conforme con la llegada de Omar De Felippe como DT?&#8221;<\/strong>, fue la pregunta que se hizo en el sitio para el hincha de Independiente. <strong>2.173 personas votaron y la diferencia entre las dos opciones a votar fue abrumadora. El 82% vot\u00f3 estar conforme con la contrataci\u00f3n del entrenador, mientras que el 18% restante se mostr\u00f3 en contra.<\/strong><\/p>\n<p>Omar De Felippe lleva dos partidos al mando del &#8220;Rojo&#8221;, con un empate como local y una victoria como visitante.<strong> Hasta ahora, la valla est\u00e1 invicta y su equipo s\u00f3lo marc\u00f3 un gol. Habr\u00e1 que darle tiempo para ver los frutos de su trabajo, pero a priori, los hinchas lo apoyan.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LocoXelRojo realiz\u00f3 una encuesta para los hinchas de Independiente respecto de sus sensaciones en cuanto a la llegada de Omar De Felippe a Independiente. Los resultados fueron contundentes: el nuevo entrenador tiene banca de parte del hincha. &#8220;\u00bfEst\u00e1s conforme con la llegada de Omar De Felippe como DT?&#8221;, fue la pregunta que se hizo en [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":36260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[782,2032],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/36259"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=36259"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/36259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/36260"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=36259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=36259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=36259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}