{"id":39311,"date":"2014-01-06T22:26:59","date_gmt":"2014-01-07T01:26:59","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=39311"},"modified":"2014-01-06T22:26:59","modified_gmt":"2014-01-07T01:26:59","slug":"se-fue-sin-pena-ni-gloria","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2014\/01\/06\/se-fue-sin-pena-ni-gloria\/","title":{"rendered":"Se fue sin pena ni gloria"},"content":{"rendered":"<p><strong>Christian N\u00fa\u00f1ez firm\u00f3 la rescisi\u00f3n de su contrato con Independiente<\/strong> y ya no tiene nada m\u00e1s que ver con la instituci\u00f3n. El uruguayo se fue sin pena ni gloria.<\/p>\n<p>Hab\u00eda llegado en el final del mercado de pases para encarar la B Nacional con un contrato por un a\u00f1o. Sin embargo, particip\u00f3 muy poco de los primeros 21 partidos del &#8220;Rojo&#8221;: <strong>jug\u00f3 cuatro partidos, dos como titular y complet\u00f3 255 minutos. Adem\u00e1s, fue amonestado dos veces.<\/strong><\/p>\n<p><strong>&#8220;Pich\u00f3n&#8221;, que no ten\u00eda lugar como titular y pretend\u00eda jugar, presion\u00f3 para partir y Omar De Felippe no opuso resistencia.<\/strong> As\u00ed, el uruguayo firm\u00f3 su desvinculaci\u00f3n y le dijo adi\u00f3s a su corto paso por el club.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Christian N\u00fa\u00f1ez firm\u00f3 la rescisi\u00f3n de su contrato con Independiente y ya no tiene nada m\u00e1s que ver con la instituci\u00f3n. El uruguayo se fue sin pena ni gloria. Hab\u00eda llegado en el final del mercado de pases para encarar la B Nacional con un contrato por un a\u00f1o. Sin embargo, particip\u00f3 muy poco de [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":39312,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[2270],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/39311"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=39311"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/39311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/39312"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=39311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=39311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=39311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}