{"id":45585,"date":"2014-07-30T13:48:58","date_gmt":"2014-07-30T16:48:58","guid":{"rendered":"http:\/\/www.locoxelrojo.com.ar\/independiente\/?p=45585"},"modified":"2014-07-30T13:48:58","modified_gmt":"2014-07-30T16:48:58","slug":"se-acerca","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2014\/07\/30\/se-acerca\/","title":{"rendered":"Se acerca"},"content":{"rendered":"<p>Esta ma\u00f1ana hubo una reuni\u00f3n entre la dirigencia de Independiente y<strong> el representante de Germ\u00e1n Montoya y, seg\u00fan le confirm\u00f3 el mismo representante a LocoXelRojo, se acord\u00f3 de palabra la llegada del arquero.<\/strong><\/p>\n<p>A un d\u00eda del cierre del mercado de pases, el Rojo trata de completar el plantel con los pedidos que hizo Jorge Almir\u00f3n. <strong>Uno de ellos era un arquero, en principio suplente y de categor\u00eda. Germ\u00e1n Montoya, de 31 a\u00f1os, tuvo un gran torneo en Col\u00f3n y decidi\u00f3 quedar con el pase en su poder.<\/strong><\/p>\n<p>Al estar libre, se facilit\u00f3 la negociaci\u00f3n y la Comisi\u00f3n Directiva lo fue a buscar. <strong>Anoche llegaron Montoya y su representante a Buenos Aires y esta ma\u00f1ana hubo una reuni\u00f3n en la que se &#8220;avanz\u00f3 much\u00edsimo&#8221;. De no ocurrir nada extra\u00f1o, Germ\u00e1n Montoya se transformar\u00e1 en nuevo refuerzo de Independiente.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana hubo una reuni\u00f3n entre la dirigencia de Independiente y el representante de Germ\u00e1n Montoya y, seg\u00fan le confirm\u00f3 el mismo representante a LocoXelRojo, se acord\u00f3 de palabra la llegada del arquero. A un d\u00eda del cierre del mercado de pases, el Rojo trata de completar el plantel con los pedidos que hizo Jorge [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":45586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[153,2740,2739],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/45585"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=45585"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/45585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/45586"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=45585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=45585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=45585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}