{"id":69105,"date":"2017-03-01T14:29:46","date_gmt":"2017-03-01T17:29:46","guid":{"rendered":"http:\/\/www.locoxelrojo.com\/independiente\/?p=69105"},"modified":"2017-03-01T14:29:46","modified_gmt":"2017-03-01T17:29:46","slug":"centrales-improvisados-efectivos","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2017\/03\/01\/centrales-improvisados-efectivos\/","title":{"rendered":"Centrales improvisados, pero efectivos"},"content":{"rendered":"<p>Por las lesiones de Alan Franco y Nicol\u00e1s Figal, <strong>Leonel \u00c1lvarez y Juan S\u00e1nchez Mi\u00f1o fue la dupla de centrales en el amistoso de los suplentes con Nueva Chicago.<\/strong><\/p>\n<p>Un puesto que escasea en Independiente son los marcadores centrales. A la salida de Hern\u00e1n Pellerano y V\u00edctor Cuesta, hay que sumarle los imprevistos que surgieron hoy con las sobrecargas musculares de Franco y Figal. Adem\u00e1s, hay que recordar que Juan Di Lorenzo, uno de los juveniles promovidos por Ariel Holan, reci\u00e9n se reincorpora a los entrenamientos tras estar internado un tiempo largo por una afecci\u00f3n pulmonar.<\/p>\n<p>Por eso, <strong>N\u00e9stor Breitenbruch y Juli\u00e1n Vitale jugaron para el equipo titular<\/strong>, y, a la hora de armar el once inicial de los suplentes, <strong>el entrenador tuvo que improvisar con \u00c1lvarez y S\u00e1nchez Mino, quienes habitualmente comparten equipo, pero en la mitad de cancha<\/strong>.<\/p>\n<p>Sin embargo, los suplentes se llevaron el triunfo por 1-0 (con un penal dudoso que Mart\u00edn Ben\u00edtez cambio por gol) y la dupla de centrales no sufri\u00f3 mayores sobresaltos. Todo lo contrario,<strong> S\u00e1nchez Mi\u00f1o tuvo una destacada actuaci\u00f3n y fue de lo mejor del equipo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por las lesiones de Alan Franco y Nicol\u00e1s Figal, Leonel \u00c1lvarez y Juan S\u00e1nchez Mi\u00f1o fue la dupla de centrales en el amistoso de los suplentes con Nueva Chicago. Un puesto que escasea en Independiente son los marcadores centrales. A la salida de Hern\u00e1n Pellerano y V\u00edctor Cuesta, hay que sumarle los imprevistos que surgieron [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69106,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3247,3],"tags":[2245,2998,247,3190,2286,1590,3369],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/69105"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=69105"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/69105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/69106"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=69105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=69105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=69105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}