{"id":69269,"date":"2017-03-16T17:21:21","date_gmt":"2017-03-16T20:21:21","guid":{"rendered":"http:\/\/www.locoxelrojo.com\/independiente\/?p=69269"},"modified":"2017-03-16T18:08:29","modified_gmt":"2017-03-16T21:08:29","slug":"ensayo-tactico-algunas-dudas","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2017\/03\/16\/ensayo-tactico-algunas-dudas\/","title":{"rendered":"Ensayo t\u00e1ctico con algunas dudas"},"content":{"rendered":"<p><strong>El plantel de Independiente se entren\u00f3 en Villa Dom\u00ednico y Ariel Holan empez\u00f3 a ensayar variantes\u00a0para el debut contra\u00a0San Mart\u00edn de San Juan.<\/strong><\/p>\n<p>Despu\u00e9s de una serie de\u00a0trabajos en el gimnasio, el entrenador organiz\u00f3 ejercicios t\u00e1cticos y prob\u00f3 una formaci\u00f3n con\u00a0<strong>Mart\u00edn Campa\u00f1a; Fabricio Bustos, Nicol\u00e1s Figal, Alan Franco, Nicol\u00e1s Tagliafico; Emiliano Rigoni, Nery Dom\u00ednguez, Walter Erviti, Gast\u00f3n Togni; Lucas Albertengo y Emmanuel Gigliotti<\/strong>.<\/p>\n<p>El t\u00e9cnico todav\u00eda mantiene algunas dudas para armar el once que saldr\u00e1 a la cancha en el Libertadores de Am\u00e9rica. Como\u00a0<a href=\"https:\/\/www.locoxelrojo.com\/independiente\/2017\/03\/16\/rechazaron-la-habilitacion-nery-dominguez\/\">Dom\u00ednguez\u00a0todav\u00eda\u00a0no est\u00e1\u00a0habilitado para jugar<\/a>, <strong>Diego Rodr\u00edguez podr\u00eda reemplazarlo en el mediocampo<\/strong> como volante central, mientras que, en defensa, <strong>Bustos y Dami\u00e1n Mart\u00ednez pelean por un lugar<\/strong> en la banda derecha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El plantel de Independiente se entren\u00f3 en Villa Dom\u00ednico y Ariel Holan empez\u00f3 a ensayar variantes\u00a0para el debut contra\u00a0San Mart\u00edn de San Juan. Despu\u00e9s de una serie de\u00a0trabajos en el gimnasio, el entrenador organiz\u00f3 ejercicios t\u00e1cticos y prob\u00f3 una formaci\u00f3n con\u00a0Mart\u00edn Campa\u00f1a; Fabricio Bustos, Nicol\u00e1s Figal, Alan Franco, Nicol\u00e1s Tagliafico; Emiliano Rigoni, Nery Dom\u00ednguez, Walter [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":69270,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3247,3],"tags":[2998,951,3235,26,1027,3371,172],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/69269"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=69269"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/69269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/69270"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=69269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=69269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=69269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}