{"id":69970,"date":"2017-04-29T13:00:27","date_gmt":"2017-04-29T16:00:27","guid":{"rendered":"http:\/\/www.locoxelrojo.com\/independiente\/?p=69970"},"modified":"2017-05-01T17:42:42","modified_gmt":"2017-05-01T20:42:42","slug":"fin-semana-descanso","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2017\/04\/29\/fin-semana-descanso\/","title":{"rendered":"Fin de semana de descanso"},"content":{"rendered":"<p><a href=\"https:\/\/www.locoxelrojo.com\/independiente\/2017\/04\/28\/no-corta-pincha\/\">Tras la igualdad 2-2 entre Independiente y Estudiantes<\/a>, <strong>el plantel fue licenciado durante el fin de semana debido a que la pr\u00f3xima semana se viene otro rival complicado: Newell&#8217;s<\/strong>.<\/p>\n<p>El Rojo visita el pr\u00f3ximo domingo a la Lepra\u00a0en Rosario y si quiere seguir en pelea por entrar a la Libertadores tiene que ganar. Para este duelo, <strong>el equipo dirigido por Ariel Holan comenzar\u00e1 su semana el lunes 1 de mayo, es decir, tendr\u00e1 s\u00e1bado y domingo libre<\/strong>.<\/p>\n<p>Ser\u00e1 una nueva prueba, como la de ayer, para saber si el conjunto de Avellaneda est\u00e1 a la altura de los rivales de primera l\u00ednea como lo son Estudiantes, Newell&#8217;s y la siguiente semana, Racing. <strong>Se vienen 15 d\u00edas determinantes para Independiente.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la igualdad 2-2 entre Independiente y Estudiantes, el plantel fue licenciado durante el fin de semana debido a que la pr\u00f3xima semana se viene otro rival complicado: Newell&#8217;s. El Rojo visita el pr\u00f3ximo domingo a la Lepra\u00a0en Rosario y si quiere seguir en pelea por entrar a la Libertadores tiene que ganar. Para este [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":69972,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3247,3],"tags":[26,1683],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/69970"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=69970"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/69970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/69972"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=69970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=69970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=69970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}