{"id":72466,"date":"2017-09-05T10:19:23","date_gmt":"2017-09-05T13:19:23","guid":{"rendered":"http:\/\/www.locoxelrojo.com\/independiente\/?p=72466"},"modified":"2017-09-05T10:20:32","modified_gmt":"2017-09-05T13:20:32","slug":"gabbarini-independiente-va-pelear-campeonato","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2017\/09\/05\/gabbarini-independiente-va-pelear-campeonato\/","title":{"rendered":"Gabbarini: &#8220;Independiente va a pelear el campeonato&#8221;"},"content":{"rendered":"<p><strong>Adri\u00e1n Gabbarini<\/strong>, arquero de Olimpo, se refiri\u00f3 al partidazo que jug\u00f3 el conjunto de Bah\u00eda Blanca ante Racing y\u00a0elogi\u00f3\u00a0al equipo de Ariel Holan, con quien se medir\u00e1 el pr\u00f3ximo viernes en el Estadio Roberto Carminatti.<\/p>\n<p><strong>&#8220;Fue muy lindo ganarle a Racing. Nos pusieron muchas trabas.\u00a0Parec\u00eda que ten\u00edan que ganar ellos pero se dio como ten\u00eda que ser&#8221;<\/strong>, expres\u00f3 en di\u00e1logo con Orgullo Rojo Radio en referencia a la victoria 4-2 contra el equipo de Diego Cocca por Copa Argentina.<\/p>\n<p>Luego el futbolista de 31 a\u00f1os palpit\u00f3 el duelo contra el Rojo: <strong>&#8220;Creo que nos vamos a encontrar con un Independiente m\u00e1s parecido a lo que jug\u00f3 Boca que Racing porque saben a qu\u00e9 juegan&#8221;<\/strong>. Y a\u00f1adi\u00f3: <strong>&#8220;Se respeta mucho a Independiente, est\u00e1 muy bien parado y sin dudas, va a pelear el campeonato&#8221;<\/strong>.<\/p>\n<p>Por otra parte, Gabbarini manifest\u00f3 su deseo de que concurra el p\u00fablico del Rojo a Bah\u00eda Blanca. <strong>&#8220;Ac\u00e1 hay mucha gente de Independiente, hay una pe\u00f1a muy grande. Ser\u00eda muy lindo que pueda haber visitantes&#8221;<\/strong>, desliz\u00f3.<\/p>\n<p>Y sobre el final\u00a0volvi\u00f3 a remarcar sus ganas de volver a vestir la camiseta del club de sus amores. <strong>&#8220;Mi etapa en Independiente fue muy buena. Tengo los videos para mostrarle a mi hijo. Siempre tengo ganas de volver. La \u00faltima vez no me quiso largar Tigre pero es lindo que te tengan en cuenta&#8221;<\/strong>, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adri\u00e1n Gabbarini, arquero de Olimpo, se refiri\u00f3 al partidazo que jug\u00f3 el conjunto de Bah\u00eda Blanca ante Racing y\u00a0elogi\u00f3\u00a0al equipo de Ariel Holan, con quien se medir\u00e1 el pr\u00f3ximo viernes en el Estadio Roberto Carminatti. &#8220;Fue muy lindo ganarle a Racing. Nos pusieron muchas trabas.\u00a0Parec\u00eda que ten\u00edan que ganar ellos pero se dio como ten\u00eda [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":72467,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3280,3247],"tags":[77],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/72466"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=72466"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/72466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/72467"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=72466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=72466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=72466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}