{"id":75451,"date":"2018-02-03T22:29:56","date_gmt":"2018-02-04T01:29:56","guid":{"rendered":"http:\/\/www.locoxelrojo.com\/independiente\/?p=75451"},"modified":"2018-02-04T15:49:42","modified_gmt":"2018-02-04T18:49:42","slug":"puntajes-rojos-vs-colon-6-1","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2018\/02\/03\/puntajes-rojos-vs-colon-6-1\/","title":{"rendered":"Puntajes Rojos vs. Col\u00f3n"},"content":{"rendered":"<p>Mart\u00edn Campa\u00f1a (7): Hoy cada vez que le toc\u00f3 jugar con los pies lo hizo simple. Buen partido del capit\u00e1n, volvi\u00f3 a la valla invicta y tuvo una tapada clave a Vera. <\/p>\n<p>Fabricio Bustos (5.5): Mejor en ataque que en defensa, donde en varios tramos del partido se vio desbordado. <\/p>\n<p>Alan Franco (7): Fuerte, seguro y firme en defensa. Gran cierre en el complemento. <\/p>\n<p>Nicol\u00e1s Figal (5.5): Aceptable partido del central. Sin complicaciones y jugando simple. <\/p>\n<p>Juan S\u00e1nchez Mi\u00f1o (6): Debe ser el lateral izquierdo. Firme en la marca y con peso en ataque por su carril.<\/p>\n<p>Diego Rodr\u00edguez Berrini (6): Seguro con la pelota en los pies y firme en la marca. Buen partido.<\/p>\n<p>Nicol\u00e1s Domingo (5): Bien el la marca y los relevos, pero algo inseguro en los pases y salidas desde el fondo. <\/p>\n<p>Maximiliano Meza (5): Segundo partido consecutivo en donde se lo vio apagado. Cuando el no aparece el Rojo lo siente. <\/p>\n<p><strong>Jonathan Men\u00e9ndez (7.5): Desequilibrante, siempre intentando desbordar y gener\u00f3 el penal del triunfo. Muy buen debut del ex Talleres. La figura de la cancha.<\/strong> <\/p>\n<p>Leandro Fern\u00e1ndez (6.5): Peligroso c\u00f3mo siempre. Marc\u00f3 el penal que le dio la victoria al Rojo. <\/p>\n<p>Emmanuel Gigliotti (5): No fue un buen partido del Puma. Se lo vio muy solo, mostr\u00f3 poco juego asociado. Se retir\u00f3 en el complemento algo enojado. <\/p>\n<p>Fernando Gaibor (5): Entr\u00f3 por Gigliotti e intent\u00f3 generar juego. Le falta agarrar el ritmo vertiginoso que suele tener el equipo.<\/p>\n<p>Mart\u00edn Ben\u00edtez (-): Sum\u00f3 minutos de f\u00fatbol despu\u00e9s de la lesi\u00f3n. <\/p>\n<p>Jon\u00e1s Guti\u00e9rrez (-): Ingres\u00f3 por Rodr\u00edguez en los \u00faltimos minutos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mart\u00edn Campa\u00f1a (7): Hoy cada vez que le toc\u00f3 jugar con los pies lo hizo simple. Buen partido del capit\u00e1n, volvi\u00f3 a la valla invicta y tuvo una tapada clave a Vera. Fabricio Bustos (5.5): Mejor en ataque que en defensa, donde en varios tramos del partido se vio desbordado. Alan Franco (7): Fuerte, seguro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":75454,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[11,3247],"tags":[153,3751,2992,3559],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/75451"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=75451"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/75451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/75454"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=75451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=75451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=75451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}