{"id":84015,"date":"2019-07-17T11:11:51","date_gmt":"2019-07-17T14:11:51","guid":{"rendered":"http:\/\/www.locoxelrojo.com\/independiente\/?p=84015"},"modified":"2019-07-17T14:34:20","modified_gmt":"2019-07-17T17:34:20","slug":"hattrick-de-romero-para-los-suplentes","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2019\/07\/17\/hattrick-de-romero-para-los-suplentes\/","title":{"rendered":"Hattrick de Romero para los suplentes"},"content":{"rendered":"<p><a href=\"https:\/\/www.locoxelrojo.com\/independiente\/2019\/07\/17\/el-equipo-de-la-copa-perdio-con-newells\/\">Luego de la derrota en el primer partido<\/a>, <strong>los suplentes de Independiente vencieron 3-0 a Newell&#8217;s con un triplete de Silvio Romero<\/strong>.<\/p>\n<p>Para el segundo encuentro que se disput\u00f3 en el Libertadores de Am\u00e9rica ante la Lepra, Sebasti\u00e1n Beccacece cambi\u00f3 \u00edntegramente el equipo. \u00bfC\u00f3mo form\u00f3 el Rojo? <strong>Milton \u00c1lvarez; Jonathan Men\u00e9ndez, Francisco Silva, Alexander Barboza, Sergio Barreto; Pablo P\u00e9rez, Carlos Benav\u00eddez, Alan So\u00f1ora; Domingo Blanco, Romero y Alan Velasco<\/strong>.<\/p>\n<p>Al igual que el primer partido se disputaron dos tiempos de 40 minutos. <strong>En la primera mitad, el Chino puso el 1-0 de cabeza. Los otros dos goles llegaron en el complemento: el segundo fue de penal y el tercero de zurda<\/strong>.<\/p>\n<p>Cabe destacar que para este amistoso <strong>sumaron minutos Gonzalo Ver\u00f3n, Andr\u00e9s Roa, Brian Mart\u00ednez y Lucas Gonz\u00e1lez<\/strong>, quienes ingresaron por Men\u00e9ndez, P\u00e9rez, So\u00f1ora y Velasco.<\/p>\n<p><strong>Los \u00fanicos que no hicieron f\u00fatbol fueron Cristian Ch\u00e1vez y Gast\u00f3n Togni<\/strong>, ambos con rutinas de trabajos espec\u00edficas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de la derrota en el primer partido, los suplentes de Independiente vencieron 3-0 a Newell&#8217;s con un triplete de Silvio Romero. Para el segundo encuentro que se disput\u00f3 en el Libertadores de Am\u00e9rica ante la Lepra, Sebasti\u00e1n Beccacece cambi\u00f3 \u00edntegramente el equipo. \u00bfC\u00f3mo form\u00f3 el Rojo? Milton \u00c1lvarez; Jonathan Men\u00e9ndez, Francisco Silva, Alexander Barboza, [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":84016,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3247,3],"tags":[2245,153,247,2831,1806],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/84015"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=84015"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/84015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/84016"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=84015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=84015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=84015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}