{"id":84934,"date":"2019-09-14T18:00:21","date_gmt":"2019-09-14T21:00:21","guid":{"rendered":"http:\/\/www.locoxelrojo.com\/independiente\/?p=84934"},"modified":"2019-09-14T15:20:30","modified_gmt":"2019-09-14T18:20:30","slug":"asi-llega-lanus-7","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2019\/09\/14\/asi-llega-lanus-7\/","title":{"rendered":"As\u00ed llega Lan\u00fas"},"content":{"rendered":"<p><strong>Independiente recibir\u00e1 a un Granate que hab\u00eda comenzado el torneo complicado por el descenso, pero a fuerza de buenos resultados pudo alejarse moment\u00e1neamente de esa zona y ser uno de los equipos que pelean por la punta del torneo.<\/strong><\/p>\n<p>Lan\u00fas parece haber encontrado la f\u00f3rmula con<strong> una mezcla de viejos conocidos y de j\u00f3venes de las inferiores que prometen<\/strong>. Bajo las \u00f3rdenes de Lu\u00eds Zubeld\u00eda y la experiencia de Jos\u00e9 Sand (dos ex Racing) y de Lautaro Acosta, junto a jugadores emergentes como Tom\u00e1s Belmonte, Facundo Quign\u00f3n, Lucas Vera, Pedro De la Vega y refuerzos con pasado en clubes grandes como Agust\u00edn Rossi, Ezequiel Mu\u00f1oz y Carlos Auzqui, los del Sur <strong>armaron una base y una idea de juego que les est\u00e1 dando resultado<\/strong>.<\/p>\n<p>El Grana se ubica en el 4\u00ba lugar de la tabla de posiciones, clasificando a la siguiente Copa Libertadores, con 10 unidades, producto de <strong>3 victorias, 1 empate y 1 derrota<\/strong>. Viene de conseguir esos<strong> tres triunfos de manera consecutiva ante V\u00e9lez, Uni\u00f3n y Central C\u00f3rdoba (SDE)<\/strong>.<\/p>\n<p>Adem\u00e1s, el \u00faltimo fin de semana <strong>pas\u00f3 a los cuartos de final de la Copa Argentina<\/strong> tras vencer 4-1 a Argentinos Juniors, <strong>y espera por el Rojo o Defensa y Justicia<\/strong> en esa instancia.<\/p>\n<p>Los probables once para visitar a Independiente en Avellaneda ser\u00edan\u00a0<strong>Agust\u00edn Rossi;\u00a0Leonel Di Pl\u00e1cido,\u00a0Ezequiel Mu\u00f1oz, Lautaro Valenti, Nicol\u00e1s Pasquini;\u00a0Tom\u00e1s Belmonte, Facundo Quign\u00f3n;\u00a0Lucas Vera,\u00a0Carlos Auzqui; Luciano Acosta y Jos\u00e9 Sand<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Independiente recibir\u00e1 a un Granate que hab\u00eda comenzado el torneo complicado por el descenso, pero a fuerza de buenos resultados pudo alejarse moment\u00e1neamente de esa zona y ser uno de los equipos que pelean por la punta del torneo. Lan\u00fas parece haber encontrado la f\u00f3rmula con una mezcla de viejos conocidos y de j\u00f3venes de [&hellip;]<\/p>\n","protected":false},"author":101017,"featured_media":84936,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1990,3247],"tags":[3275,326,4195],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/84934"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/101017"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=84934"}],"version-history":[{"count":0,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/84934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/84936"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=84934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=84934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=84934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}