{"id":93000,"date":"2021-01-27T14:57:38","date_gmt":"2021-01-27T17:57:38","guid":{"rendered":"http:\/\/www.locoxelrojo.com\/independiente\/?p=93000"},"modified":"2021-01-27T16:13:56","modified_gmt":"2021-01-27T19:13:56","slug":"todos-negativos","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2021\/01\/27\/todos-negativos\/","title":{"rendered":"Todos negativos"},"content":{"rendered":"<p>En la previa del entrenamiento de este mi\u00e9rcoles en Villa Dom\u00ednico, <strong>el plantel de Independiente fue hisopado y los resultados no arrojaron ning\u00fan positivo<\/strong>.<\/p>\n<p>De acuerdo con las normas establecidas, el Rojo volvi\u00f3 a someterse a los estudios generales para determinar si hab\u00eda alg\u00fan jugador con Covid-19. Estos tests obligatorios vienen siendo peri\u00f3dicos desde que retorn\u00f3 el f\u00fatbol.<\/p>\n<p><strong>Para tranquilidad de Julio Falcioni todos sus dirigidos dieron negativo<\/strong>. <a href=\"https:\/\/www.locoxelrojo.com\/independiente\/2021\/01\/27\/se-entreno-con-una-cara-nueva\/\">Esto permiti\u00f3 que en la pr\u00e1ctica de hoy<\/a>, el entrenador del Rey de Copas pueda contar con <strong>Sebasti\u00e1n Palacios<\/strong> tras haber dirimido cuestiones econ\u00f3micas con la Comisi\u00f3n Directiva.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"es\" dir=\"ltr\">Todo bien y a seguir &#x1f44a;&#x1f3fb;<\/p>\n<p>El Plantel Profesional fue hisopado esta ma\u00f1ana y todos los resultados dieron negativos a COVID-19.<a href=\"https:\/\/twitter.com\/hashtag\/TodoRojo?src=hash&amp;ref_src=twsrc%5Etfw\">#TodoRojo<\/a> &#x1f534; <a href=\"https:\/\/t.co\/3pnC0kifmD\">pic.twitter.com\/3pnC0kifmD<\/a><\/p>\n<p>&mdash; C. A. Independiente (@Independiente) <a href=\"https:\/\/twitter.com\/Independiente\/status\/1354440808783638531?ref_src=twsrc%5Etfw\">January 27, 2021<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la previa del entrenamiento de este mi\u00e9rcoles en Villa Dom\u00ednico, el plantel de Independiente fue hisopado y los resultados no arrojaron ning\u00fan positivo. De acuerdo con las normas establecidas, el Rojo volvi\u00f3 a someterse a los estudios generales para determinar si hab\u00eda alg\u00fan jugador con Covid-19. Estos tests obligatorios vienen siendo peri\u00f3dicos desde que [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":93001,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3247,3],"tags":[153,4506,4512,385,3432],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/93000"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=93000"}],"version-history":[{"count":1,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/93000\/revisions"}],"predecessor-version":[{"id":93002,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/93000\/revisions\/93002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/93001"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=93000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=93000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=93000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}