{"id":93035,"date":"2021-01-28T17:07:34","date_gmt":"2021-01-28T20:07:34","guid":{"rendered":"http:\/\/www.locoxelrojo.com\/independiente\/?p=93035"},"modified":"2021-01-28T19:22:27","modified_gmt":"2021-01-28T22:22:27","slug":"cecchini-seria-un-sueno-poder-jugar-en-independiente","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2021\/01\/28\/cecchini-seria-un-sueno-poder-jugar-en-independiente\/","title":{"rendered":"Cecchini: &#8220;Ser\u00eda un sue\u00f1o poder jugar en Independiente&#8221;"},"content":{"rendered":"<p><strong>Emanuel Cechini es uno de los nombres que entreg\u00f3 Julio C\u00e9sar Falcioni para reforzar el mediocampo del Rojo.<\/strong> El entrenador busca alguien que acompa\u00f1e a Lucas Romero y los que m\u00e1s fuerza tomaron fueron los dirigidos por \u00e9l en su paso por el Taladro.<\/p>\n<p><strong>&#8220;Ser\u00eda un sue\u00f1o poder jugar en Independiente, ojal\u00e1 se pueda dar&#8221;<\/strong>, coment\u00f3 el futbolista que jug\u00f3 la \u00faltima temporada en Uni\u00f3n, haciendo claramente fuerzas para llegar al Rey de Copas.2<\/p>\n<p>El centrocampista, que ten\u00eda contrato con el M\u00e1laga, rescindi\u00f3 y se encuentra libre, por lo que desde Avellaneda iniciaron charlas informales para conocer su situaci\u00f3n:<strong> &#8220;Se que se comunicaron con mi representante, pero nada concreto&#8221;.<\/strong><\/p>\n<p><strong>&#8220;Con Julio hace bastante que no hablo&#8221;<\/strong>, concluy\u00f3 el volante de 24 a\u00f1os en di\u00e1logo con el programa radial, Contragolpe, dando a conocer que todav\u00eda no recibi\u00f3 un llamado del flamante nuevo DT de la instituci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Emanuel Cechini es uno de los nombres que entreg\u00f3 Julio C\u00e9sar Falcioni para reforzar el mediocampo del Rojo. El entrenador busca alguien que acompa\u00f1e a Lucas Romero y los que m\u00e1s fuerza tomaron fueron los dirigidos por \u00e9l en su paso por el Taladro. &#8220;Ser\u00eda un sue\u00f1o poder jugar en Independiente, ojal\u00e1 se pueda dar&#8221;, [&hellip;]<\/p>\n","protected":false},"author":101025,"featured_media":93038,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3280,3247],"tags":[153,4770,385,1665],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/93035"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/101025"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=93035"}],"version-history":[{"count":1,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/93035\/revisions"}],"predecessor-version":[{"id":93039,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/93035\/revisions\/93039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/93038"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=93035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=93035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=93035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}