{"id":98526,"date":"2021-08-01T12:26:55","date_gmt":"2021-08-01T15:26:55","guid":{"rendered":"https:\/\/www.locoxelrojo.com\/independiente\/?p=98526"},"modified":"2021-08-01T15:38:27","modified_gmt":"2021-08-01T18:38:27","slug":"le-costo-por-izquierda","status":"publish","type":"post","link":"https:\/\/www.locoxelrojo.com\/independiente\/2021\/08\/01\/le-costo-por-izquierda\/","title":{"rendered":"Le cost\u00f3 por izquierda"},"content":{"rendered":"<p><strong>Thomas Ortega fue titular en Independiente en reemplazo de Lucas Rodr\u00edguez<\/strong>, quien estaba lesionado. Sin embargo tuvo muchas complicaciones por su carril.<\/p>\n<p>No es la primera vez que le sucede. El lateral izquierdo arranc\u00f3 muy dormido en el partido, Platense aprovech\u00f3 y opt\u00f3 atacar por su sector. De hecho, el gol del local lleg\u00f3 por esa banda. <strong>Una desatenci\u00f3n del juvenil de 20 a\u00f1os que nunca reaccion\u00f3 tras la p\u00e9rdida de Sebasti\u00e1n Palacios<\/strong>.<\/p>\n<p>El experimentado Facundo Curuchet le hizo la noche dif\u00edcil por izquierda y a\u00fan m\u00e1s cuando se complement\u00f3 con Augusto Schott, donde el defensor de Independiente quedaba en inferioridad num\u00e9rica.<\/p>\n<p><strong>Ortega jug\u00f3 los 90 minutos y dio 47 pases correctos (77%)<\/strong>. <strong>En cuanto a duelos<\/strong> (terrestres y a\u00e9reos) <strong>tuvo 11, de los cuales gan\u00f3 6<\/strong>. A su vez, <strong>perdi\u00f3 21 veces la pelota y cometi\u00f3 2 infracciones<\/strong>. En ataque, pr\u00e1cticamente no fue part\u00edcipe de las jugadas del Rojo. <strong>No concret\u00f3 ninguno de los 3 centros que intent\u00f3 y, adem\u00e1s, acert\u00f3 1 de los 4 balones en largo<\/strong>. Poca efectividad.<\/p>\n<p>La \u00faltima vez que el juvenil de 20 a\u00f1os jug\u00f3 desde el arranque hab\u00eda sido el 27 de mayo, en la victoria 1-0 ante Guabir\u00e1 por Copa Sudamericana. Desde entonces, disput\u00f3 apenas tres minutos en cinco encuentros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thomas Ortega fue titular en Independiente en reemplazo de Lucas Rodr\u00edguez, quien estaba lesionado. Sin embargo tuvo muchas complicaciones por su carril. No es la primera vez que le sucede. El lateral izquierdo arranc\u00f3 muy dormido en el partido, Platense aprovech\u00f3 y opt\u00f3 atacar por su sector. De hecho, el gol del local lleg\u00f3 por [&hellip;]<\/p>\n","protected":false},"author":101027,"featured_media":98531,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[4943,3247],"tags":[153,3398,4088,4947],"_links":{"self":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/98526"}],"collection":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/users\/101027"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/comments?post=98526"}],"version-history":[{"count":1,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/98526\/revisions"}],"predecessor-version":[{"id":98527,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/posts\/98526\/revisions\/98527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media\/98531"}],"wp:attachment":[{"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/media?parent=98526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/categories?post=98526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locoxelrojo.com\/independiente\/wp-json\/wp\/v2\/tags?post=98526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}